{"id":836,"date":"2018-02-13T11:08:16","date_gmt":"2018-02-13T11:08:16","guid":{"rendered":"http:\/\/psicologiacolmenar.es\/psicologo\/?p=836"},"modified":"2018-10-04T09:54:46","modified_gmt":"2018-10-04T09:54:46","slug":"maltrato-infantil-factores-de-riesgo","status":"publish","type":"post","link":"https:\/\/www.psicologiacolmenar.es\/psicologo\/maltrato-infantil-factores-de-riesgo\/","title":{"rendered":"<h2>Maltrato infantil<\/h2> <h4>Factores de riesgo<\/h4>"},"content":{"rendered":"<p>Se han descrito una serie de situaciones familiares y personales que ocurren de manera m\u00e1s frecuente en las familias en las que aparecen casos de <strong>maltrato infantil<\/strong>, por tanto, estas se consideran,<\/p>\n<p><strong>Factores de riesgo<\/strong>, entre ellas est\u00e1n:<\/p>\n<ul>\n<li>Historia de maltrato f\u00edsico en la infancia: las experiencias infantiles de maltrato constituyen una predisposici\u00f3n a que la relaci\u00f3n con los propios hijos sea inadecuada o maltratante.<\/li>\n<li>Ausencia de apoyo social: diversos estudios plantean la posibilidad de que los padres maltratantes posean una red deficitaria de apoyo social.<\/li>\n<li>Problemas en los padres maltratantes: situaciones como el <a href=\"http:\/\/psicologiacolmenar.es\/psicologo\/abuso-de-alcohol-y-sus-perjuicios\/\" target=\"_blank\" rel=\"noopener\">abuso de alcohol<\/a>, las toxicoman\u00edas, las alteraciones psicol\u00f3gicas o la baja autoestima suele estar presentes en los sujetos con problemas de maltrato hacia sus hijos.<\/li>\n<li>Parece frecuente que en los padres o madres maltratantes se encuentren, normalmente, sentimientos de incapacidad para mejorar su vida y su situaci\u00f3n personal lo que puede colaborar a reducir sus posibilidades de hacer frente de manera efectiva a las situaciones de crisis.<\/li>\n<\/ul>\n<p><strong>Tipolog\u00edas de maltrato infantil<\/strong><\/p>\n<p>Breve descripci\u00f3n de las m\u00e1s importantes y frecuentes:<\/p>\n<ul>\n<li>Maltrato f\u00edsico: cualquier acci\u00f3n no accidental por parte de los padres o tutores que provoque da\u00f1os f\u00edsicos severos, enfermedad en el menor o le coloquen en grave riesgo de padecerlo. Incluye agresi\u00f3n f\u00edsica, administraci\u00f3n de drogas alcohol y f\u00e1rmacos potencialmente peligrosos, y utilizaci\u00f3n de castigos gravemente inapropiados.<\/li>\n<li>Negligencia f\u00edsica: las necesidades f\u00edsicas, de seguridad o formativas b\u00e1sicas del menor no son atendidas de manera adecuada por ning\u00fan miembro del grupo que convive con \u00e9l y sus padres o tutores. La situaci\u00f3n se presenta de forma continuada. Aunque uno o ambos padres o tutores muestren conductas negligentes, si hay otras personas adultas en la unidad familiar que se ocupan de satisfacer las necesidades del menor, la situaci\u00f3n no se suele calificar como negligencia.<\/li>\n<li>Maltrato emocional: falta persistente de respuesta a las se\u00f1ales, expresiones emocionales y conductas procuradoras de proximidad e interacci\u00f3n iniciadas por el menor, y falta de iniciativa de interacci\u00f3n y contacto, por parte de una figura adulta estable. Incluye la negligencia hacia necesidades de interacci\u00f3n y afecto, hacia necesidades de atenci\u00f3n espec\u00edfica de problemas emocionales y hacia necesidades de normas, l\u00edmites y valores positivos.<\/li>\n<li><a href=\"https:\/\/www.iberley.es\/temas\/regimen-juridico-delito-abusos-sexuales-48201\" target=\"_blank\" rel=\"noopener\">Abuso sexual<\/a>: cualquier clase de contacto e interacci\u00f3n sexual entre los padres o tutores y el menor en la que el adulto, que por definici\u00f3n posee una posici\u00f3n de poder o autoridad sobre el menor, usa a \u00e9ste para su propia estimulaci\u00f3n sexual, la del menor o la de otra persona.<\/li>\n<li>Incapacidad parental de control de la conducta del menor: los padres o tutores hacen dejaci\u00f3n de su responsabilidad de controlar y manejar de manera adaptativa el comportamiento del menor. Incluye la incapacidad de controlar y manejar problemas serios de comportamiento en el domicilio familiar o conductas altamente problem\u00e1ticas y desadaptadas que el menor presenta fuera del domicilio familiar.<\/li>\n<\/ul>\n<p><a href=\"http:\/\/psicologiacolmenar.es\/psicologo\/quien-soy-psicologo-en-colmenar-viejo-centro-de-psicologia-gabinete-de-psicologos\/\" target=\"_blank\" rel=\"noopener\">J. Miguel San Mart\u00edn Rodr\u00edguez. Psic\u00f3logo sanitario<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se han descrito una serie de situaciones familiares y personales que ocurren de manera m\u00e1s frecuente en las familias en las que aparecen casos de maltrato infantil, por tanto, estas se consideran, Factores de riesgo, entre ellas est\u00e1n: Historia de maltrato f\u00edsico en la infancia: las experiencias infantiles de maltrato constituyen una predisposici\u00f3n a que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":837,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[309,308,306],"tags":[183,94,57,182,180,179,181],"class_list":["post-836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-familia","category-infancia-y-adolescencia","category-trastornos-emocionales","tag-abuso-sexual","tag-apoyo-social","tag-maltrato","tag-maltrato-emocinal","tag-maltrato-fisico","tag-maltrato-infantil","tag-negligencia-fisica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v19.2.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Maltrato infantil - Psicologos en Colmenar Viejo Madrid<\/title>\n<meta name=\"description\" content=\"Existen una serie de situaciones familiares y personales que ocurren de manera m\u00e1s frecuente en las familias en las que aparecen casos de maltrato infantil\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.psicologiacolmenar.es\/psicologo\/maltrato-infantil-factores-de-riesgo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maltrato infantil\" \/>\n<meta property=\"og:description\" content=\"Se han descrito una serie de situaciones familiares y personales que ocurren de manera m\u00e1s frecuente en las familias en las que aparecen casos de maltrato\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.psicologiacolmenar.es\/psicologo\/maltrato-infantil-factores-de-riesgo\/\" \/>\n<meta property=\"og:site_name\" content=\"Psicologos en Colmenar Viejo Madrid\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/psicologocolmenar\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-13T11:08:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-04T09:54:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-content\/uploads\/2018\/02\/MALTRATO-INFANTIL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"920\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Psicologo Colmenar Viejo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jmsanmartinps1\" \/>\n<meta name=\"twitter:site\" content=\"@jmsanmartinps1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Psicologo Colmenar Viejo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/maltrato-infantil-factores-de-riesgo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/maltrato-infantil-factores-de-riesgo\\\/\"},\"author\":{\"name\":\"Psicologo Colmenar Viejo\",\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/#\\\/schema\\\/person\\\/c14b55b6ab94baa638c4e455b0f5efcd\"},\"headline\":\"Maltrato infantil Factores de riesgo\",\"datePublished\":\"2018-02-13T11:08:16+00:00\",\"dateModified\":\"2018-10-04T09:54:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/maltrato-infantil-factores-de-riesgo\\\/\"},\"wordCount\":518,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/maltrato-infantil-factores-de-riesgo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/MALTRATO-INFANTIL.jpg\",\"keywords\":[\"abuso sexual\",\"apoyo social\",\"maltrato\",\"maltrato emocinal\",\"maltrato f\u00edsico\",\"maltrato infantil\",\"negligencia f\u00edsica\"],\"articleSection\":[\"FAMILIA\",\"INFANCIA Y ADOLESCENCIA\",\"TRASTORNOS EMOCIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/maltrato-infantil-factores-de-riesgo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/maltrato-infantil-factores-de-riesgo\\\/\",\"url\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/maltrato-infantil-factores-de-riesgo\\\/\",\"name\":\"Maltrato infantil - Psicologos en Colmenar Viejo Madrid\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/maltrato-infantil-factores-de-riesgo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/maltrato-infantil-factores-de-riesgo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/MALTRATO-INFANTIL.jpg\",\"datePublished\":\"2018-02-13T11:08:16+00:00\",\"dateModified\":\"2018-10-04T09:54:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/#\\\/schema\\\/person\\\/c14b55b6ab94baa638c4e455b0f5efcd\"},\"description\":\"Existen una serie de situaciones familiares y personales que ocurren de manera m\u00e1s frecuente en las familias en las que aparecen casos de maltrato infantil\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/maltrato-infantil-factores-de-riesgo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/maltrato-infantil-factores-de-riesgo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/maltrato-infantil-factores-de-riesgo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/MALTRATO-INFANTIL.jpg\",\"contentUrl\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/MALTRATO-INFANTIL.jpg\",\"width\":920,\"height\":682,\"caption\":\"maltrato infantil\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/maltrato-infantil-factores-de-riesgo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maltrato infantil Factores de riesgo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/#website\",\"url\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/\",\"name\":\"Psicologos en Colmenar Viejo Madrid\",\"description\":\"Gabinete de psicologos y Centro de psicolog\u00eda en Colmenar Viejo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/#\\\/schema\\\/person\\\/c14b55b6ab94baa638c4e455b0f5efcd\",\"name\":\"Psicologo Colmenar Viejo\",\"url\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/author\\\/psicologo-colmenar-viejo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Maltrato infantil - Psicologos en Colmenar Viejo Madrid","description":"Existen una serie de situaciones familiares y personales que ocurren de manera m\u00e1s frecuente en las familias en las que aparecen casos de maltrato infantil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.psicologiacolmenar.es\/psicologo\/maltrato-infantil-factores-de-riesgo\/","og_locale":"es_ES","og_type":"article","og_title":"Maltrato infantil","og_description":"Se han descrito una serie de situaciones familiares y personales que ocurren de manera m\u00e1s frecuente en las familias en las que aparecen casos de maltrato","og_url":"https:\/\/www.psicologiacolmenar.es\/psicologo\/maltrato-infantil-factores-de-riesgo\/","og_site_name":"Psicologos en Colmenar Viejo Madrid","article_publisher":"https:\/\/www.facebook.com\/psicologocolmenar\/","article_published_time":"2018-02-13T11:08:16+00:00","article_modified_time":"2018-10-04T09:54:46+00:00","og_image":[{"width":920,"height":682,"url":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-content\/uploads\/2018\/02\/MALTRATO-INFANTIL.jpg","type":"image\/jpeg"}],"author":"Psicologo Colmenar Viejo","twitter_card":"summary_large_image","twitter_creator":"@jmsanmartinps1","twitter_site":"@jmsanmartinps1","twitter_misc":{"Escrito por":"Psicologo Colmenar Viejo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/maltrato-infantil-factores-de-riesgo\/#article","isPartOf":{"@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/maltrato-infantil-factores-de-riesgo\/"},"author":{"name":"Psicologo Colmenar Viejo","@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/#\/schema\/person\/c14b55b6ab94baa638c4e455b0f5efcd"},"headline":"Maltrato infantil Factores de riesgo","datePublished":"2018-02-13T11:08:16+00:00","dateModified":"2018-10-04T09:54:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/maltrato-infantil-factores-de-riesgo\/"},"wordCount":518,"commentCount":0,"image":{"@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/maltrato-infantil-factores-de-riesgo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-content\/uploads\/2018\/02\/MALTRATO-INFANTIL.jpg","keywords":["abuso sexual","apoyo social","maltrato","maltrato emocinal","maltrato f\u00edsico","maltrato infantil","negligencia f\u00edsica"],"articleSection":["FAMILIA","INFANCIA Y ADOLESCENCIA","TRASTORNOS EMOCIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.psicologiacolmenar.es\/psicologo\/maltrato-infantil-factores-de-riesgo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/maltrato-infantil-factores-de-riesgo\/","url":"https:\/\/www.psicologiacolmenar.es\/psicologo\/maltrato-infantil-factores-de-riesgo\/","name":"Maltrato infantil - Psicologos en Colmenar Viejo Madrid","isPartOf":{"@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/maltrato-infantil-factores-de-riesgo\/#primaryimage"},"image":{"@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/maltrato-infantil-factores-de-riesgo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-content\/uploads\/2018\/02\/MALTRATO-INFANTIL.jpg","datePublished":"2018-02-13T11:08:16+00:00","dateModified":"2018-10-04T09:54:46+00:00","author":{"@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/#\/schema\/person\/c14b55b6ab94baa638c4e455b0f5efcd"},"description":"Existen una serie de situaciones familiares y personales que ocurren de manera m\u00e1s frecuente en las familias en las que aparecen casos de maltrato infantil","breadcrumb":{"@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/maltrato-infantil-factores-de-riesgo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.psicologiacolmenar.es\/psicologo\/maltrato-infantil-factores-de-riesgo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/maltrato-infantil-factores-de-riesgo\/#primaryimage","url":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-content\/uploads\/2018\/02\/MALTRATO-INFANTIL.jpg","contentUrl":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-content\/uploads\/2018\/02\/MALTRATO-INFANTIL.jpg","width":920,"height":682,"caption":"maltrato infantil"},{"@type":"BreadcrumbList","@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/maltrato-infantil-factores-de-riesgo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.psicologiacolmenar.es\/psicologo\/"},{"@type":"ListItem","position":2,"name":"Maltrato infantil Factores de riesgo"}]},{"@type":"WebSite","@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/#website","url":"https:\/\/www.psicologiacolmenar.es\/psicologo\/","name":"Psicologos en Colmenar Viejo Madrid","description":"Gabinete de psicologos y Centro de psicolog\u00eda en Colmenar Viejo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.psicologiacolmenar.es\/psicologo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/#\/schema\/person\/c14b55b6ab94baa638c4e455b0f5efcd","name":"Psicologo Colmenar Viejo","url":"https:\/\/www.psicologiacolmenar.es\/psicologo\/author\/psicologo-colmenar-viejo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/posts\/836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/comments?post=836"}],"version-history":[{"count":2,"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/posts\/836\/revisions"}],"predecessor-version":[{"id":1013,"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/posts\/836\/revisions\/1013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/media\/837"}],"wp:attachment":[{"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/media?parent=836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/categories?post=836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/tags?post=836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}