{"id":843,"date":"2018-02-16T12:24:09","date_gmt":"2018-02-16T12:24:09","guid":{"rendered":"http:\/\/psicologiacolmenar.es\/psicologo\/?p=843"},"modified":"2019-06-10T18:00:40","modified_gmt":"2019-06-10T18:00:40","slug":"abuso-de-alcohol-y-sus-perjuicios","status":"publish","type":"post","link":"https:\/\/www.psicologiacolmenar.es\/psicologo\/abuso-de-alcohol-y-sus-perjuicios\/","title":{"rendered":"<h2>Abuso de alcohol y sus perjuicios<\/h2> <h4>Efectos en los menores<\/h4>"},"content":{"rendered":"<h2><strong>Alcohol: efectos en el organismo<\/strong><\/h2>\n<p>El alcohol es una sustancia adictiva y su consumo prolongado puede causar problemas en nuestra salud f\u00edsica y psicol\u00f3gica.<\/p>\n<p>Es cierto que el consumo moderado de alcohol puede no traer estos perjuicios, pero es una sustancia que hace trabajar en exceso nuestro h\u00edgado para poder metabolizarla.<\/p>\n<p>Nuestro organismo se ve seriamente da\u00f1ado, en muchos aspectos, por el consumo prolongado de alcohol. El h\u00edgado, el coraz\u00f3n, el cerebro se ven seriamente perjudicados.<\/p>\n<p>El cerebro se ve afectado con p\u00e9rdidas de memoria y confusi\u00f3n. Los nervios perif\u00e9ricos del sistema nervioso tambi\u00e9n se ven afectados causando cambios en la sensibilidad y percepci\u00f3n.<\/p>\n<p>La funci\u00f3n del h\u00edgado es la de eliminar el alcohol del organismo, pero en exceso, hace que el h\u00edgado no sea capaz de asimilar esas cantidades, llegando a causar uno de los problemas t\u00edpicos del consumo de alcohol que puede llevar al fallecimiento: la cirrosis.<\/p>\n<p>Aun siendo totalmente legales, el alcohol es tan perjudicial o m\u00e1s que otras drogas como la marihuana o la coca\u00edna.<\/p>\n<p>Los efectos destructivos del alcohol a nivel social son muchos, ya que destroza familias, matrimonios, amistades, se puede llegar a perder el trabajo, el dinero y todo lo que se tiene.<\/p>\n<p>Otro aspecto importante es la influencia del consumo de alcohol, en adultos, sobre los menores, que aprenden de forma vicaria, ese habito como algo normal y herramienta clave para las relaciones sociales, de tal manera que, llegada la adolescencia, no se concibe la diversi\u00f3n sin el consumo de alcohol a edades cada vez m\u00e1s tempranas.<\/p>\n<h2><strong>Efectos del alcohol en los menores<\/strong><\/h2>\n<p>Pero \u00bfcu\u00e1les son los efectos del alcohol en los menores?<\/p>\n<p>Consumir alcohol en la infancia y en la adolescencia es nocivo, independientemente de la cantidad o la frecuencia con que se haga.<\/p>\n<p>Iniciar el consumo de alcohol antes de los 18 a\u00f1os aumenta la probabilidad de continuarlo en la edad adulta, as\u00ed como la de recurrir a otras drogas como la marihuana o la coca\u00edna.<\/p>\n<p>El consumo de alcohol en menores de 18 a\u00f1os puede influir de manera negativa en el desarrollo del cerebro. El cerebro termina su maduraci\u00f3n a los 21 a\u00f1os, por lo tanto, no puede asimilar el alcohol de la misma manera que un adulto.<\/p>\n<p>Cuando un adolescente toma y adem\u00e1s abusa del alcohol, es vulnerable, adem\u00e1s, a otros riesgos que afectan su salud y bienestar, como, por ejemplo:<br \/>\n\u2022 Alteraciones en el desarrollo y crecimiento de los huesos<br \/>\n\u2022 Mayor predisposici\u00f3n a enfermedades respiratorias<br \/>\n\u2022 Mayor susceptibilidad a contraer infecciones<br \/>\n\u2022 Trastornos del sistema endocrino: disminuci\u00f3n de la producci\u00f3n de la hormona del crecimiento (GH) encargada no s\u00f3lo del crecimiento y el desarrollo sino tambi\u00e9n de los procesos de diferenciaci\u00f3n sexual y maduraci\u00f3n en la pubertad<br \/>\n\u2022 Retardo en la maduraci\u00f3n de los caracteres sexuales secundarios<br \/>\n\u2022 Trastornos cardiovasculares<br \/>\n\u2022 Trastornos g\u00e1stricos: irritaciones en la pared intestinal que aumentan la probabilidad de desarrollar gastritis, v\u00f3mito y alteraciones del tr\u00e1nsito intestinal<br \/>\n\u2022 C\u00e1ncer<\/p>\n<p>Tambi\u00e9n se encuentran otros tipos de riesgos o da\u00f1os asociados al consumo de alcohol durante la infancia y la adolescencia:<br \/>\n\u2022 Mayor probabilidad de desarrollar problemas del estado del \u00e1nimo, como depresi\u00f3n o ansiedad<br \/>\n\u2022 Aumento en la probabilidad de realizar conductas sexuales de riesgo que pueden llevarlos a contraer enfermedades de transmisi\u00f3n sexual y embarazos no deseados<br \/>\n\u2022 Mayor probabilidad de ser v\u00edctima de delitos como violaci\u00f3n, robo y agresi\u00f3n<br \/>\n\u2022 Dificultades acad\u00e9micas (ausentismo, dificultades en el aprendizaje, etc.)<\/p>\n<h2><strong>Evaluaci\u00f3n del consumo de alcohol<\/strong><\/h2>\n<p>En el siguiente link, se accede al <a href=\"https:\/\/psicologiacolmenar.es\/psicologo\/test-de-consumo-de-alcohol\/\" target=\"_blank\" rel=\"noopener\">Cuestionario de Identificaci\u00f3n de Trastornos por consumo de alcohol.<\/a><\/p>\n<p>Puntuaciones entre 8 y 15 sugieren orientaci\u00f3n profesional para reducir el consumo de alcohol.<br \/>\nPuntuaciones entre 16 y 19, requieren terapia y un abordaje continuado.<br \/>\nPuntuaciones mayores de 20 puntos, requieren una evaluaci\u00f3n diagnostica m\u00e1s amplia por un problema de dependencia al alcohol.<\/p>\n<p><a href=\"https:\/\/psicologiacolmenar.es\/psicologo\/psicologo-colmenar-viejo\/\" target=\"_blank\" rel=\"noopener\">J. Miguel San Mart\u00edn<\/a>. Psic\u00f3logo sanitario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alcohol: efectos en el organismo El alcohol es una sustancia adictiva y su consumo prolongado puede causar problemas en nuestra salud f\u00edsica y psicol\u00f3gica. Es cierto que el consumo moderado de alcohol puede no traer estos perjuicios, pero es una sustancia que hace trabajar en exceso nuestro h\u00edgado para poder metabolizarla. Nuestro organismo se ve [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":844,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[309,308,310],"tags":[187,184,190,189,191,192,188],"class_list":["post-843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-familia","category-infancia-y-adolescencia","category-otros-trastornos","tag-abuso","tag-alcohol","tag-alteraciones-emocionales","tag-cirrosis","tag-drogas","tag-drogodependencias","tag-menores"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v19.2.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Abuso de alcohol y sus perjuicios - Psicologos en Colmenar Viejo Madrid<\/title>\n<meta name=\"description\" content=\"El alcohol es una sustancia adictiva y su consumo prolongado puede causar problemas en nuestra salud f\u00edsica y psicol\u00f3gica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.psicologiacolmenar.es\/psicologo\/abuso-de-alcohol-y-sus-perjuicios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abuso de alcohol y sus perjuicios\" \/>\n<meta property=\"og:description\" content=\"Alcohol: efectos en el organismo El alcohol es una sustancia adictiva y su consumo prolongado puede causar problemas en nuestra salud f\u00edsica y\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.psicologiacolmenar.es\/psicologo\/abuso-de-alcohol-y-sus-perjuicios\/\" \/>\n<meta property=\"og:site_name\" content=\"Psicologos en Colmenar Viejo Madrid\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/psicologocolmenar\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-16T12:24:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-10T18:00:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-content\/uploads\/2018\/02\/ALCOHOL.2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1149\" \/>\n\t<meta property=\"og:image:height\" content=\"765\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Psicologo Colmenar Viejo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jmsanmartinps1\" \/>\n<meta name=\"twitter:site\" content=\"@jmsanmartinps1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Psicologo Colmenar Viejo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/abuso-de-alcohol-y-sus-perjuicios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/abuso-de-alcohol-y-sus-perjuicios\\\/\"},\"author\":{\"name\":\"Psicologo Colmenar Viejo\",\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/#\\\/schema\\\/person\\\/c14b55b6ab94baa638c4e455b0f5efcd\"},\"headline\":\"Abuso de alcohol y sus perjuicios Efectos en los menores\",\"datePublished\":\"2018-02-16T12:24:09+00:00\",\"dateModified\":\"2019-06-10T18:00:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/abuso-de-alcohol-y-sus-perjuicios\\\/\"},\"wordCount\":677,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/abuso-de-alcohol-y-sus-perjuicios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/ALCOHOL.2.jpg\",\"keywords\":[\"abuso\",\"alcohol\",\"alteraciones emocionales\",\"cirrosis\",\"drogas\",\"drogodependencias\",\"menores\"],\"articleSection\":[\"FAMILIA\",\"INFANCIA Y ADOLESCENCIA\",\"OTROS TRASTORNOS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/abuso-de-alcohol-y-sus-perjuicios\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/abuso-de-alcohol-y-sus-perjuicios\\\/\",\"url\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/abuso-de-alcohol-y-sus-perjuicios\\\/\",\"name\":\"Abuso de alcohol y sus perjuicios - Psicologos en Colmenar Viejo Madrid\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/abuso-de-alcohol-y-sus-perjuicios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/abuso-de-alcohol-y-sus-perjuicios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/ALCOHOL.2.jpg\",\"datePublished\":\"2018-02-16T12:24:09+00:00\",\"dateModified\":\"2019-06-10T18:00:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/#\\\/schema\\\/person\\\/c14b55b6ab94baa638c4e455b0f5efcd\"},\"description\":\"El alcohol es una sustancia adictiva y su consumo prolongado puede causar problemas en nuestra salud f\u00edsica y psicol\u00f3gica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/abuso-de-alcohol-y-sus-perjuicios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/abuso-de-alcohol-y-sus-perjuicios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/abuso-de-alcohol-y-sus-perjuicios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/ALCOHOL.2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/ALCOHOL.2.jpg\",\"width\":1149,\"height\":765,\"caption\":\"ABUSO ALCOHOL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/abuso-de-alcohol-y-sus-perjuicios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abuso de alcohol y sus perjuicios Efectos en los menores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/#website\",\"url\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/\",\"name\":\"Psicologos en Colmenar Viejo Madrid\",\"description\":\"Gabinete de psicologos y Centro de psicolog\u00eda en Colmenar Viejo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/#\\\/schema\\\/person\\\/c14b55b6ab94baa638c4e455b0f5efcd\",\"name\":\"Psicologo Colmenar Viejo\",\"url\":\"https:\\\/\\\/www.psicologiacolmenar.es\\\/psicologo\\\/author\\\/psicologo-colmenar-viejo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Abuso de alcohol y sus perjuicios - Psicologos en Colmenar Viejo Madrid","description":"El alcohol es una sustancia adictiva y su consumo prolongado puede causar problemas en nuestra salud f\u00edsica y psicol\u00f3gica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.psicologiacolmenar.es\/psicologo\/abuso-de-alcohol-y-sus-perjuicios\/","og_locale":"es_ES","og_type":"article","og_title":"Abuso de alcohol y sus perjuicios","og_description":"Alcohol: efectos en el organismo El alcohol es una sustancia adictiva y su consumo prolongado puede causar problemas en nuestra salud f\u00edsica y","og_url":"https:\/\/www.psicologiacolmenar.es\/psicologo\/abuso-de-alcohol-y-sus-perjuicios\/","og_site_name":"Psicologos en Colmenar Viejo Madrid","article_publisher":"https:\/\/www.facebook.com\/psicologocolmenar\/","article_published_time":"2018-02-16T12:24:09+00:00","article_modified_time":"2019-06-10T18:00:40+00:00","og_image":[{"width":1149,"height":765,"url":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-content\/uploads\/2018\/02\/ALCOHOL.2.jpg","type":"image\/jpeg"}],"author":"Psicologo Colmenar Viejo","twitter_card":"summary_large_image","twitter_creator":"@jmsanmartinps1","twitter_site":"@jmsanmartinps1","twitter_misc":{"Escrito por":"Psicologo Colmenar Viejo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/abuso-de-alcohol-y-sus-perjuicios\/#article","isPartOf":{"@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/abuso-de-alcohol-y-sus-perjuicios\/"},"author":{"name":"Psicologo Colmenar Viejo","@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/#\/schema\/person\/c14b55b6ab94baa638c4e455b0f5efcd"},"headline":"Abuso de alcohol y sus perjuicios Efectos en los menores","datePublished":"2018-02-16T12:24:09+00:00","dateModified":"2019-06-10T18:00:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/abuso-de-alcohol-y-sus-perjuicios\/"},"wordCount":677,"commentCount":0,"image":{"@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/abuso-de-alcohol-y-sus-perjuicios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-content\/uploads\/2018\/02\/ALCOHOL.2.jpg","keywords":["abuso","alcohol","alteraciones emocionales","cirrosis","drogas","drogodependencias","menores"],"articleSection":["FAMILIA","INFANCIA Y ADOLESCENCIA","OTROS TRASTORNOS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.psicologiacolmenar.es\/psicologo\/abuso-de-alcohol-y-sus-perjuicios\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/abuso-de-alcohol-y-sus-perjuicios\/","url":"https:\/\/www.psicologiacolmenar.es\/psicologo\/abuso-de-alcohol-y-sus-perjuicios\/","name":"Abuso de alcohol y sus perjuicios - Psicologos en Colmenar Viejo Madrid","isPartOf":{"@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/abuso-de-alcohol-y-sus-perjuicios\/#primaryimage"},"image":{"@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/abuso-de-alcohol-y-sus-perjuicios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-content\/uploads\/2018\/02\/ALCOHOL.2.jpg","datePublished":"2018-02-16T12:24:09+00:00","dateModified":"2019-06-10T18:00:40+00:00","author":{"@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/#\/schema\/person\/c14b55b6ab94baa638c4e455b0f5efcd"},"description":"El alcohol es una sustancia adictiva y su consumo prolongado puede causar problemas en nuestra salud f\u00edsica y psicol\u00f3gica.","breadcrumb":{"@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/abuso-de-alcohol-y-sus-perjuicios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.psicologiacolmenar.es\/psicologo\/abuso-de-alcohol-y-sus-perjuicios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/abuso-de-alcohol-y-sus-perjuicios\/#primaryimage","url":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-content\/uploads\/2018\/02\/ALCOHOL.2.jpg","contentUrl":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-content\/uploads\/2018\/02\/ALCOHOL.2.jpg","width":1149,"height":765,"caption":"ABUSO ALCOHOL"},{"@type":"BreadcrumbList","@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/abuso-de-alcohol-y-sus-perjuicios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.psicologiacolmenar.es\/psicologo\/"},{"@type":"ListItem","position":2,"name":"Abuso de alcohol y sus perjuicios Efectos en los menores"}]},{"@type":"WebSite","@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/#website","url":"https:\/\/www.psicologiacolmenar.es\/psicologo\/","name":"Psicologos en Colmenar Viejo Madrid","description":"Gabinete de psicologos y Centro de psicolog\u00eda en Colmenar Viejo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.psicologiacolmenar.es\/psicologo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.psicologiacolmenar.es\/psicologo\/#\/schema\/person\/c14b55b6ab94baa638c4e455b0f5efcd","name":"Psicologo Colmenar Viejo","url":"https:\/\/www.psicologiacolmenar.es\/psicologo\/author\/psicologo-colmenar-viejo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/posts\/843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/comments?post=843"}],"version-history":[{"count":3,"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/posts\/843\/revisions"}],"predecessor-version":[{"id":1161,"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/posts\/843\/revisions\/1161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/media\/844"}],"wp:attachment":[{"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/media?parent=843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/categories?post=843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psicologiacolmenar.es\/psicologo\/wp-json\/wp\/v2\/tags?post=843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}